{"id":8428,"date":"2022-05-18T09:27:01","date_gmt":"2022-05-18T07:27:01","guid":{"rendered":"https:\/\/www.domaine-prairiesdelamer.com\/?p=8428"},"modified":"2024-06-10T15:24:49","modified_gmt":"2024-06-10T13:24:49","slug":"les-prairies-de-la-mer-awards","status":"publish","type":"post","link":"https:\/\/mirabel-prairiesdelamer.com\/en\/2022\/05\/18\/les-prairies-de-la-mer-recompenses\/","title":{"rendered":"Prairies de la Mer wins award"},"content":{"rendered":"<p class=\"has-text-align-center texte-rond has-orange-color has-text-color has-large-font-size wp-block-paragraph\">8\/10 for our camping trip in Ouistreham!<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 21%\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"595\" src=\"https:\/\/www.mirabel-prairiesdelamer.com\/wp-content\/uploads\/2022\/05\/c2be-awards-2022-prairies-de-la-mer-1.jpeg\" alt=\"\" class=\"wp-image-8435 size-full\" srcset=\"https:\/\/mirabel-prairiesdelamer.com\/wp-content\/uploads\/2022\/05\/c2be-awards-2022-prairies-de-la-mer-1.jpeg 420w, https:\/\/mirabel-prairiesdelamer.com\/wp-content\/uploads\/2022\/05\/c2be-awards-2022-prairies-de-la-mer-1-212x300.jpeg 212w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">The \u00abCamping2be Award\u00bb recognizes the highest-rated campsites each season. In 2021, Camping Les Prairies de la Mer received a rating of <strong>8,76\/10<\/strong> thanks to your advice and feedback. As such, we have been awarded the <strong>Camping2be Award 2022<\/strong> ! <br><br>So we wanted to thank you very warmly for your kindness and your loyalty over so many years! We will continue to do everything we can to welcome you in the best conditions and give you the most wonderful vacation possible.<br><br>See you soon at the Prairies de la Mer! <\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>8\/10 pour notre camping \u00e0 Ouistreham ! Le \u00ab\u00a0Camping2be Award\u00a0\u00bb r\u00e9compense les campings les mieux not\u00e9s de chaque saison. En [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8447,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"Notre camping r\u00e9compens\u00e9 dans le Calvados","_seopress_titles_desc":"Le \"Camping2be Award\" r\u00e9compense les campings les mieux not\u00e9s de chaque saison. En 2021, le Camping Les Prairies de la Mer a re\u00e7u la note de 8,76\/10","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/posts\/8428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/comments?post=8428"}],"version-history":[{"count":11,"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/posts\/8428\/revisions"}],"predecessor-version":[{"id":13801,"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/posts\/8428\/revisions\/13801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/media\/8447"}],"wp:attachment":[{"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/media?parent=8428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/categories?post=8428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mirabel-prairiesdelamer.com\/en\/wp-json\/wp\/v2\/tags?post=8428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}